{"id":58456,"date":"2021-04-13T09:24:26","date_gmt":"2021-04-23T16:10:40","guid":{"rendered":"http:\/\/www.showagroup.com\/shop\/240"},"modified":"2026-04-13T14:36:21","modified_gmt":"2026-04-13T12:36:21","slug":"240","status":"publish","type":"product","link":"https:\/\/www.showagroup.com\/eu-es\/shop\/240\/","title":{"rendered":"240"},"content":{"rendered":"<p>Los guantes resistentes al fuego 240 de SHOWA son perfectos para la soldadura TIG y MIG ligera.<\/p>\n<p>Con la protecci\u00f3n contra el arco el\u00e9ctrico de clase 2, las manos est\u00e1n protegidas de llamas, fogonazos y chispas, para evitar quemaduras.<\/p>\n<p>Su calificaci\u00f3n de destreza de nivel 5 de la normativa EN420 garantiza control y precisi\u00f3n cuando se trabaja en proyectos a peque\u00f1a escala.<\/p>\n<p>Estos guantes tambi\u00e9n son resistentes a los cortes, no irritan y tienen un agarre de superficie rugosa, lo que proporciona una excelente comodidad cuando se trabaja durante largos per\u00edodos de tiempo.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":63390,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":["post-58456","product","type-product","status-publish","has-post-thumbnail","region-au","region-br","region-eu","region-la","region-na","region-ca","region-sa-eu-es","first","instock","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/product\/58456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/comments?post=58456"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/media\/63390"}],"wp:attachment":[{"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/media?parent=58456"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/product_brand?post=58456"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/product_cat?post=58456"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.showagroup.com\/eu-es\/wp-json\/wp\/v2\/product_tag?post=58456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}